{"id":9,"count":42,"description":"","link":"https:\/\/blog.otto-schmidt.de\/gesellschaftsrecht\/category\/gesellschaftsrecht\/","name":"Gesellschaftsrecht","slug":"gesellschaftsrecht","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/blog.otto-schmidt.de\/gesellschaftsrecht\/wp-json\/wp\/v2\/categories\/9"}],"collection":[{"href":"https:\/\/blog.otto-schmidt.de\/gesellschaftsrecht\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blog.otto-schmidt.de\/gesellschaftsrecht\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/blog.otto-schmidt.de\/gesellschaftsrecht\/wp-json\/wp\/v2\/posts?categories=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}