{"id":2132,"date":"2022-02-15T11:32:13","date_gmt":"2022-02-15T10:32:13","guid":{"rendered":"https:\/\/blog.otto-schmidt.de\/mdr\/?p=2132"},"modified":"2022-02-15T11:32:13","modified_gmt":"2022-02-15T10:32:13","slug":"olg-frankfurt-m-die-spaete-absetzung-eines-schiedsspruchs-fuehrt-nicht-zur-aufhebung","status":"publish","type":"post","link":"https:\/\/blog.otto-schmidt.de\/mdr\/2022\/02\/15\/olg-frankfurt-m-die-spaete-absetzung-eines-schiedsspruchs-fuehrt-nicht-zur-aufhebung\/","title":{"rendered":"OLG Frankfurt\/M.: Die sp\u00e4te Absetzung eines Schiedsspruchs f\u00fchrt nicht zur Aufhebung"},"content":{"rendered":"<p>Einige wichtige Gesichtspunkte, die bei Schiedsverfahren zu beachten sind, hat das OLG Frankfurt\/M., Beschl. v. 17.5.2021 \u2013 <a href=\"https:\/\/online.otto-schmidt.de\/db\/dokument?id=rs.olgfrankfurt.20210517.26sch1\/21\">26 Sch 1\/21<\/a> erfreulicherweise gekl\u00e4rt.<\/p>\n<p>Ein a<strong>d-hoc Schiedsgericht<\/strong> verurteilte die jetzige Antragstellerin des Aufhebungsverfahrens vor dem OLG zur Zahlung von gut 3 Millionen Euro. Die Antragstellerin bem\u00fchte sich, die Aufhebung des Schiedsspruches durch das OLG zu erreichen, die Antragsgegnerin erstrebte die Vollstreckbarkeitserkl\u00e4rung. Es ging u. a. um folgende Verfahrensfragen: Das Schiedsgericht hatte am Schluss der durchgef\u00fchrten m\u00fcndlichen Verhandlung <strong>keinen Verk\u00fcndungstermin<\/strong> bestimmt. Der Schiedsspruch wurde vielmehr erst <strong>nach ungef\u00e4hr einem Jahr<\/strong> erlassen. Die Antragstellerin sah u. a. darin einen Versto\u00df gegen den ordre-public, der zur Aufhebung des Schiedsspruchs f\u00fchren m\u00fcsse.<\/p>\n<p>Das OLG folgt dem zu Recht nicht. Im Zivilprozess sind \u2013 von bestimmten Ausnahme abgesehen (z. B. \u00a7\u00a7 307, 331 ZPO) \u2013 Urteile grunds\u00e4tzlich zu verk\u00fcnden, und zwar entweder in der Sitzung, am Schluss der Sitzung oder in einem Verk\u00fcndungstermin (\u00a7\u00a7 310, 311 ZPO). Gem\u00e4\u00df \u00a7 1054 Abs. 1 ZPO ist bei einem Schiedsspruch jedoch die <strong>\u00dcbermittlung<\/strong> eines von den Schiedsrichtern unterzeichneten Schiedsspruchs <strong>ausreichend<\/strong>. Es bedarf daher<strong> keiner Verk\u00fcndung<\/strong> und auch keines Verk\u00fcndungstermins. Anders k\u00f6nnte dies nur sein, wenn die Parteien dies vereinbart h\u00e4tten oder die Schiedsordnung dies vorgesehen h\u00e4tte. Es handelt sich hier aber um ein ad-hoc-Schiedsgericht ohne besondere Vereinbarungen der Parteien zum Verfahren.<\/p>\n<p>Gem\u00e4\u00df \u00a7 310 Abs. 1 Satz 2 ZPO ist der Verk\u00fcndungstermin nur dann \u00fcber drei Wochen hinaus anzusetzen, wenn wichtige Gr\u00fcnde, insbesondere der Umfang oder die Schwierigkeit der Sache, dies erfordern. Nun war der Verfahrensgegenstand des Schiedsverfahrens sicherlich umfangreich und schwierig, ein Jahr ist aber eine lange Zeit. Gleichwohl ist <strong>\u00a7 310 ZPO<\/strong> im Schiedsgerichtsverfahren grunds\u00e4tzlich <strong>nicht anwendbar<\/strong>. Und selbst wenn: Im Schiedsgerichtsverfahren <strong>betrifft<\/strong> die sehr sp\u00e4te Absetzung eines Schiedsspruchs <strong>beide Parteien.<\/strong> Deshalb w\u00e4re es nicht sachgerecht, hier eine Aufhebungsm\u00f6glichkeit zu schaffen, die nur eine Partei beg\u00fcnstigt. Auch l\u00e4sst sich in derartigen F\u00e4llen regelm\u00e4\u00dfig kaum feststellen, dass die Verz\u00f6gerung Auswirkungen auf den Schiedsspruch gehabt hat, etwa, weil die Erinnerung an die m\u00fcndliche Verhandlung verblasst w\u00e4re. Die Parteien sind einer Verz\u00f6gerung auch nicht schutzlos ausgeliefert, sondern k\u00f6nnen einen Antrag nach \u00a7 1038 ZPO stellen.<\/p>\n<p>Die behaupteten Verfahrensfehler stehen der Wirksamkeit des Schiedsspruchs damit nicht entgegen, so dass dieser f\u00fcr vollstreckbar zu erkl\u00e4ren war.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Einige wichtige Gesichtspunkte, die bei Schiedsverfahren zu beachten sind, hat das OLG Frankfurt\/M., Beschl. v. 17.5.2021 \u2013 26 Sch 1\/21 erfreulicherweise gekl\u00e4rt. Ein ad-hoc Schiedsgericht verurteilte die jetzige Antragstellerin des Aufhebungsverfahrens vor dem OLG zur Zahlung von gut 3 Millionen Euro. Die Antragstellerin bem\u00fchte sich, die Aufhebung des Schiedsspruches durch das OLG zu erreichen, die [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1305,2],"tags":[661,2078,2077,2079],"_links":{"self":[{"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/posts\/2132"}],"collection":[{"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/comments?post=2132"}],"version-history":[{"count":2,"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/posts\/2132\/revisions"}],"predecessor-version":[{"id":2140,"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/posts\/2132\/revisions\/2140"}],"wp:attachment":[{"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/media?parent=2132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/categories?post=2132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/tags?post=2132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}