{"id":2222,"date":"2022-06-26T14:14:36","date_gmt":"2022-06-26T12:14:36","guid":{"rendered":"https:\/\/blog.otto-schmidt.de\/mdr\/?p=2222"},"modified":"2022-06-26T14:14:36","modified_gmt":"2022-06-26T12:14:36","slug":"montagsblog-247","status":"publish","type":"post","link":"https:\/\/blog.otto-schmidt.de\/mdr\/2022\/06\/26\/montagsblog-247\/","title":{"rendered":"Montagsblog: Neues vom BGH"},"content":{"rendered":"<p><em>Diese Woche geht es um das anwendbare Recht f\u00fcr Unterhaltsanspr\u00fcche eines geschiedenen Ehegatten. <\/em><\/p>\n<p><strong>Unterhaltsstatut f\u00fcr Expatriate-Ehe<br \/>\n<\/strong>Beschluss vom 11.\u00a0Mai 2022 \u2013 XII\u00a0ZB\u00a0543\/20<\/p>\n<p><em>Mit Art.\u00a05 HUP befasst sich der XII.\u00a0Zivilsenat.<\/em><\/p>\n<p>Die Antragstellerin begehrt von ihrem geschiedenen Ehemann Unterhalt in H\u00f6he von rund 5.000 Euro pro Monat. Die beiden Beteiligten sind deutsche Staatsangeh\u00f6rige. Mit ihrer 1992 geborenen Tochter lebten sie seit 1994 in Schottland, wo der Antragsgegner promovierte. Seit 1999 ist der Antragsteller f\u00fcr ein Mineral\u00f6lunternehmen t\u00e4tig. Dieses setzt ihn als so genannten Expatriate jeweils f\u00fcr befristete Zeit \u2013 in der Regel f\u00fcnf Jahre \u2013 an einem seiner internationalen Standorte ein. Von 1999 bis 2008 lebten die Beteiligten in den Niederlanden, wo sie 2006 einen Partnerschaftsvertrag nach niederl\u00e4ndischem Recht schlossen und 2008 heirateten. Von 2008 bis 2012 lebten sie im Sultanat Brunei, seit Juni 2012 in Texas. Im Jahr 2017 wurde die Ehe von einem Bezirksgericht in Texas rechtskr\u00e4ftig geschieden. Die Antragstellerin lebt seither in Deutschland, der Antragsteller weiterhin \u2013 nunmehr auf Dauer \u2013 in Texas.<\/p>\n<p>Der Antrag auf Verurteilung zur Unterhaltszahlung ist in den Vorinstanzen erfolglos geblieben, weil das nach Auffassung von AG und OLG anwendbare texanische Recht einen Unterhaltsanspruch grunds\u00e4tzlich erst nach einer Ehedauer von zehn Jahren vorsieht.<\/p>\n<p>Der BGH verweist die Sache an das OLG zur\u00fcck.<\/p>\n<p>Entgegen der Auffassung der Vorinstanzen ist der Unterhaltsanspruch nach deutschem Recht zu beurteilen.<\/p>\n<p>In den Mitgliedstaaten der EU (mit Ausnahme von D\u00e4nemark und Irland) ist das auf Unterhaltspflichten anwendbare Recht gem\u00e4\u00df Art.\u00a015 der Verordnung (EG) Nr.\u00a04\/2009 nach dem Haager Protokoll vom 23.\u00a0November 2007 \u00fcber das auf Unterhaltspflichten anzuwendende Recht (HUP) zu bestimmen.<\/p>\n<p>Nach Art.\u00a03 HUP ist f\u00fcr Unterhaltspflichten grunds\u00e4tzlich das Recht des Staates ma\u00dfgebend, in dem die berechtigte Person ihren gew\u00f6hnlichen Aufenthalt hat. Dies ist im Streitfall das deutsche Recht, weil die Antragstellerin in Deutschland wohnt.<\/p>\n<p>Entgegen der Auffassung der Vorinstanzen f\u00fchrt Art.\u00a05 HUP im Streitfall nicht zur Anwendbarkeit des texanischen Rechts. Hierf\u00fcr w\u00e4re erforderlich, dass die Ehe eine engere Verbindung zu diesem Recht aufwiese. Hieran fehlt es im Streitfall, weil der gemeinsame Aufenthalt der Eheleute in Texas \u2013 wie alle vorangegangenen Aufenthalte an anderen Orten \u2013 nicht auf Dauer angelegt war. Eine engere Verbindung als diejenige zum deutschen Recht wird auch nicht dadurch begr\u00fcndet, dass die Ehe in Texas geschieden wurde oder dass der Antragsteller sich nach der Scheidung entschlossen hat, auf Dauer dort zu leben.<\/p>\n<p><span style=\"color: #ff0000\"><em>Praxistipp:<\/em><\/span> Die Kollisionsregeln des HUP sind nach Art.\u00a02 HUP auch dann anwendbar, wenn sie zum Recht eines Staates f\u00fchren, der (wie die USA) dem Protokoll nicht beigetreten ist. Soweit keine spezielleren Regeln greifen, bilden sie deshalb (seit 18.06.2011) das f\u00fcr Deutschland ma\u00dfgebliche Kollisionsrecht f\u00fcr Unterhaltsanspr\u00fcche. Zum wesentlichen Inhalt vgl. Conti FamRBInt 2011, 62.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Diese Woche geht es um das anwendbare Recht f\u00fcr Unterhaltsanspr\u00fcche eines geschiedenen Ehegatten. Unterhaltsstatut f\u00fcr Expatriate-Ehe Beschluss vom 11.\u00a0Mai 2022 \u2013 XII\u00a0ZB\u00a0543\/20 Mit Art.\u00a05 HUP befasst sich der XII.\u00a0Zivilsenat. Die Antragstellerin begehrt von ihrem geschiedenen Ehemann Unterhalt in H\u00f6he von rund 5.000 Euro pro Monat. Die beiden Beteiligten sind deutsche Staatsangeh\u00f6rige. Mit ihrer 1992 geborenen [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[793,1857],"tags":[2168,2172,2173,2171,2170,2169,2167],"_links":{"self":[{"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/posts\/2222"}],"collection":[{"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/comments?post=2222"}],"version-history":[{"count":1,"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/posts\/2222\/revisions"}],"predecessor-version":[{"id":2223,"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/posts\/2222\/revisions\/2223"}],"wp:attachment":[{"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/media?parent=2222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/categories?post=2222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/tags?post=2222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}