{"id":242,"date":"2016-06-15T15:07:31","date_gmt":"2016-06-15T13:07:31","guid":{"rendered":"http:\/\/blog.otto-schmidt.de\/mdr\/?p=242"},"modified":"2016-06-28T17:06:59","modified_gmt":"2016-06-28T15:06:59","slug":"bgh-fehlende-herstellergarantie-kann-zum-ruecktritt-berechtigender-mangel-beim-pkw-sein","status":"publish","type":"post","link":"https:\/\/blog.otto-schmidt.de\/mdr\/2016\/06\/15\/bgh-fehlende-herstellergarantie-kann-zum-ruecktritt-berechtigender-mangel-beim-pkw-sein\/","title":{"rendered":"BGH: Fehlende Herstellergarantie kann zum R\u00fccktritt berechtigender Sachmangel beim PKW sein"},"content":{"rendered":"<p>Der BGH hat in seiner heutigen Entscheidung festgestellt, dass das Vorhandensein einer Herstellergarantie beim Gebrauchtwagenkauf ein Beschaffenheitsmerkmal der Kaufsache nach allen Tatbestandsvarianten des \u00a7 434 Abs. 1 BGB darstellt und somit zum mangelbedingten R\u00fccktritt vom Kaufvertrag berechtigen kann.<\/p>\n<p>Noch in beiden Vorinstanzen (u.a. <a href=\"http:\/\/files.vogel.de\/iww\/iww\/quellenmaterial\/dokumente\/144654.pdf\">OLG M\u00fcnchen, Beschluss vom 13.05.2015 Az.: 21 U 4559\/14<\/a>) gingen die Gerichte abweichend davon aus, dass es sich nicht um ein Beschaffenheitsmerkmal des Fahrzeuges handele, es sich bei der Zusage einer Herstellergarantie lediglich um eine Angabe zur\u00a0rechtlichen Beziehung au\u00dferhalb der Kaufsache zwischen Fahrzeughalter und Hersteller handele.<\/p>\n<p>Das Berufungsgericht hat die Sache zur\u00fcckverwiesen erhalten und wird hier\u00fcber unter W\u00fcrdigung der Ansicht des BGH zu entscheiden haben.<\/p>\n<p><strong>Ausblick \/ Praxisrelevanz:<\/strong> Bei dem Fehlen einer Herstellergarantie d\u00fcrfte es sich, so ist zu vermuten, auch um einen nicht unerheblichen Mangel halten, sodass der R\u00fccktritt vom Kaufvertrag m\u00f6glich sein d\u00fcrfte. In der Praxis zeigen sich bei Gebrauchtwagenangeboten eine Vielzahl von Hinweisen auf eine (Hersteller-)Garantie. Abgesehen davon, dass\u00a0unvollst\u00e4ndige Garantieangaben einen Wettbewerbsversto\u00df\u00a0begr\u00fcnden (<a href=\"http:\/\/portal.ovszr.de\/Default.aspx?hitnr=0&amp;t=636016036687976250&amp;url=rn%3aanwalt%5e%5efile%3a%2f%2fR%7c%2fDoc%2fMagazines%2fMDR%2f258492.xml&amp;ref=hitlist_hl\" target=\"_blank\">BGH, Urt. v. 5. 12. 2012 \u2013 I ZR 146\/11<\/a><a href=\"http:\/\/portal.ovszr.de\/Default.aspx?hitnr=0&amp;t=636016036687976250&amp;url=rn%3aanwalt%5e%5efile%3a%2f%2fR%7c%2fDoc%2fMagazines%2fMDR%2f258492.xml&amp;ref=hitlist_hl\" target=\"_blank\">\u00a0MDR 2013,\u00a01300<\/a>), ist Gebrauchtwagenh\u00e4ndlern umso mehr zu raten, die\u00a0Konditionen einer Garantie offenzulegen. Oft werden Anschlussgarantien oder Gebrauchtwagengarantien angeboten, die deutlich hinter den Leistungen von Werksgarantien z.B. im Hinblick auf abgedeckte Teile oder Selbstbeteiligungen ab gewissen Laufleistungen zur\u00fcck bleiben.<\/p>\n<p>BGH Urteil vom 15. Juni 2016 &#8211; VIII ZR 134\/15, <a href=\"http:\/\/juris.bundesgerichtshof.de\/cgi-bin\/rechtsprechung\/document.py?Gericht=bgh&amp;Art=pm&amp;Datum=2016&amp;Sort=3&amp;nr=75008&amp;pos=0&amp;anz=105\">Pressemitteilung<\/a><\/p>\n<p><strong>Update vom 28.06.2016:<\/strong> Die Entscheidung ist nun im <a href=\"http:\/\/juris.bundesgerichtshof.de\/cgi-bin\/rechtsprechung\/document.py?Gericht=bgh&amp;Art=en&amp;client=12&amp;nr=75104&amp;pos=0&amp;anz=1&amp;Blank=1.pdf\">Volltext <\/a>ver\u00f6ffentlicht<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der BGH hat in seiner heutigen Entscheidung festgestellt, dass das Vorhandensein einer Herstellergarantie beim Gebrauchtwagenkauf ein Beschaffenheitsmerkmal der Kaufsache nach allen Tatbestandsvarianten des \u00a7 434 Abs. 1 BGB darstellt und somit zum mangelbedingten R\u00fccktritt vom Kaufvertrag berechtigen kann. Noch in beiden Vorinstanzen (u.a. OLG M\u00fcnchen, Beschluss vom 13.05.2015 Az.: 21 U 4559\/14) gingen die Gerichte [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,63,60],"tags":[5,180,179,176,178,177],"_links":{"self":[{"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/posts\/242"}],"collection":[{"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/comments?post=242"}],"version-history":[{"count":5,"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/posts\/242\/revisions"}],"predecessor-version":[{"id":263,"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/posts\/242\/revisions\/263"}],"wp:attachment":[{"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/media?parent=242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/categories?post=242"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/tags?post=242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}