{"id":281,"date":"2016-07-13T13:13:27","date_gmt":"2016-07-13T11:13:27","guid":{"rendered":"http:\/\/blog.otto-schmidt.de\/mdr\/?p=281"},"modified":"2016-08-03T12:31:03","modified_gmt":"2016-08-03T10:31:03","slug":"bgh-zur-fristsetzung-zur-nacherfuellung-im-kaufrecht","status":"publish","type":"post","link":"https:\/\/blog.otto-schmidt.de\/mdr\/2016\/07\/13\/bgh-zur-fristsetzung-zur-nacherfuellung-im-kaufrecht\/","title":{"rendered":"BGH zur Fristsetzung zur Nacherf\u00fcllung im Kaufrecht"},"content":{"rendered":"<p>Der BGH hat sich in einem\u00a0Urteil vom 13. Juli 2016 &#8211; VIII ZR 49\/15 mit der Frage auseinderzusetzen, wie genau die f\u00fcr einen R\u00fccktritt erforderliche Setzung einer Nachfrist zur Nacherf\u00fcllung formuliert sein muss. Im entschiedenen Fall verwendete der K\u00e4ufer die Begrifflichkeit &#8222;unverz\u00fcglich&#8220;, ohne einen konkreten Termin des Fristendes einzusetzen. Auch formulierte er es als\u00a0<em>Bitte um &#8222;schnelle Behebung&#8220;<\/em>.<\/p>\n<p>Der BGH stellt sich dabei auf den \u00e4u\u00dferst\u00a0k\u00e4uferfreundlichen Standpunkt, dass mit\u00a0einer solchen\u00a0Formulierung dem Verk\u00e4ufer eine zeitliche Grenze gesetzt wird, die aufgrund der jeweiligen Umst\u00e4nde des Einzelfalls bestimmbar ist und ihm vor Augen f\u00fchrt, dass er die Nachbesserung nicht zu einem beliebigen Zeitpunkt bewirken darf.<\/p>\n<p>Auch H\u00f6flichkeit schadet nicht im Rechtsverkehr<\/p>\n<blockquote><p>&#8222;Trotz der gew\u00e4hlten h\u00f6flichen Bezeichnung als &#8222;Bitte&#8220; lie\u00df die Kl\u00e4gerin dabei auch keine Zweifel an der Ernsthaftigkeit des Nacherf\u00fcllungsverlangens aufkommen.&#8220;<\/p><\/blockquote>\n<p>hei\u00dft es in der Pressemitteilung.<br \/>\n<strong>Fazit:<\/strong> Eine\u00a0Nachfristsetzung als Schl\u00fcssel f\u00fcr eine Vielzahl von Sekund\u00e4ranspr\u00fcchen d\u00fcrfte\u00a0auch in &#8211; dem Wortlaut der Fristsetzung zufolge &#8211;\u00a0zweifelhaften F\u00e4llen nach dieser Rechtsprechung durchaus zu bejahen sein.<\/p>\n<p>Wie diese sehr weitreichende Auslegung mit dem Wortlaut von \u00a7 323 Abs. 1 BGB vereinbart werden kann, ist fraglich. Dort ist ausdr\u00fccklich nicht von einer einfachen Mahnung (wie z.B. \u00a7 286 Abs. 1 BGB), sondern von dem Bestimmen einer Frist die Rede.<\/p>\n<p>&nbsp;<\/p>\n<p>BGH Urteil vom 13. Juli 2016 &#8211; VIII ZR 49\/15\u00a0<a href=\"http:\/\/juris.bundesgerichtshof.de\/cgi-bin\/rechtsprechung\/document.py?Gericht=bgh&amp;Art=pm&amp;Datum=2016&amp;Sort=3&amp;nr=75265&amp;pos=0&amp;anz=121\" target=\"_blank\">Link zur Pressemitteilung \u00a0<\/a>\u00a0 <a href=\"http:\/\/juris.bundesgerichtshof.de\/cgi-bin\/rechtsprechung\/document.py?Gericht=bgh&amp;Art=en&amp;client=12&amp;nr=75498&amp;pos=0&amp;anz=1&amp;Blank=1.pdf\">Link zur Entscheidung<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der BGH hat sich in einem\u00a0Urteil vom 13. Juli 2016 &#8211; VIII ZR 49\/15 mit der Frage auseinderzusetzen, wie genau die f\u00fcr einen R\u00fccktritt erforderliche Setzung einer Nachfrist zur Nacherf\u00fcllung formuliert sein muss. Im entschiedenen Fall verwendete der K\u00e4ufer die Begrifflichkeit &#8222;unverz\u00fcglich&#8220;, ohne einen konkreten Termin des Fristendes einzusetzen. Auch formulierte er es als\u00a0Bitte um [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,15,63,60],"tags":[5,241,240,242,220,166],"_links":{"self":[{"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/posts\/281"}],"collection":[{"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/comments?post=281"}],"version-history":[{"count":3,"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/posts\/281\/revisions"}],"predecessor-version":[{"id":303,"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/posts\/281\/revisions\/303"}],"wp:attachment":[{"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/media?parent=281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/categories?post=281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/tags?post=281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}