{"id":291,"date":"2016-08-01T15:06:13","date_gmt":"2016-08-01T13:06:13","guid":{"rendered":"http:\/\/blog.otto-schmidt.de\/mdr\/?p=291"},"modified":"2016-08-01T15:06:13","modified_gmt":"2016-08-01T13:06:13","slug":"montagsblog-13","status":"publish","type":"post","link":"https:\/\/blog.otto-schmidt.de\/mdr\/2016\/08\/01\/montagsblog-13\/","title":{"rendered":"Montagsblog: Neues vom BGH"},"content":{"rendered":"<p>In Anlehnung an die sog. Montagspost beim BGH berichtet der Montagsblog w\u00f6chentlich \u00fcber ausgew\u00e4hlte aktuelle Entscheidungen.<\/p>\n<p><strong>Anwendbarkeit von \u00a7\u00a0280 und \u00a7\u00a0281 BGB im Eigent\u00fcmer-Besitzer-Verh\u00e4ltnis<br \/>\n<\/strong>Urteil vom 18. M\u00e4rz 2016 \u2013 V ZR 89\/15<\/p>\n<p><em>Eine viel diskutierte Streitfrage zum Verh\u00e4ltnis zwischen \u00a7\u00a7\u00a0985\u00a0ff. BGB und den Vorschriften des allgemeinen Schuldrechts hat der V.\u00a0Zivilsenat entschieden.<\/em><\/p>\n<p>Eine mittlerweile insolvente Gesellschaft hatte aufgrund eines Kooperationsvertrags mit einem Einkaufsring in mehreren von der Beklagten betriebenen Getr\u00e4nkem\u00e4rkten Videoger\u00e4te f\u00fcr Werbezwecke aufgestellt. Nach Beendigung des Kooperationsvertrags teilte der Kl\u00e4ger mit, die Ger\u00e4te seien an ihn \u00fcbereignet worden. Zugleich verlangte er die Herausgabe der Ger\u00e4te. Nachdem die Beklagte diesem Verlangen nicht nachgekommen war, verlangte er von ihr Schadensersatz in H\u00f6he des Ver\u00e4u\u00dferungswerts. Die Klage blieb in den ersten beiden Instanzen erfolglos.<\/p>\n<p>Der BGH verweist die Sache an das OLG zur\u00fcck. Mit den Vorinstanzen verneint er einen Schadensersatzanspruch aus \u00a7\u00a7\u00a0989, 990 BGB. Die Beklagte war zwar b\u00f6sgl\u00e4ubig, weil sie nach Beendigung des Kooperationsvertrags wusste, dass sie nicht (mehr) zum Besitz der Ger\u00e4te berechtigt ist. Der Anspruch aus \u00a7\u00a7\u00a0989, 990 BGB umfasst aber nur den Schaden, der dadurch entsteht, dass die Sache nicht mehr herausgegeben werden kann, nicht hingegen einen Schaden aufgrund blo\u00dfer Vorenthaltung der Sache. Als Grundlage f\u00fcr einen solchen Anspruch kommen in der zu beurteilenden Konstellation nur \u00a7\u00a7\u00a0280, 281 BGB in Betracht. Diese sind nach Auffassung des BGH auf den Herausgabeanspruch aus \u00a7\u00a0985 BGB anwendbar. Das in einem Teil der Literatur angef\u00fchrte Gegenargument, die Anwendung der Vorschriften laufe auf einen Zwangskauf hinaus, h\u00e4lt der BGH f\u00fcr nicht stichhaltig, weil sich eine vergleichbare Situation auch bei schuldrechtlichen R\u00fcckgabeanspr\u00fcchen ergeben kann und der Gesetzgeber dem Gl\u00e4ubiger dennoch die M\u00f6glichkeit einger\u00e4umt hat, zum Schadensersatz \u00fcberzugehen. Entsprechend der Wertung in \u00a7\u00a7\u00a0989, 990 BGB setzen Anspr\u00fcche aus \u00a7\u00a0280 und \u00a7\u00a0281 BGB wegen Verletzung der Herausgabepflicht aus \u00a7\u00a0985 BGB allerdings zus\u00e4tzlich voraus, dass der Herausgabeanspruch rechtsh\u00e4ngig oder der Besitzer b\u00f6sgl\u00e4ubig ist.<\/p>\n<p><em><span style=\"color: #ff0000\">Praxistipp:<\/span> Die Entscheidung, vom Herausgabeanspruch zum Schadensersatzanspruch \u00fcberzugehen, sollte sorgf\u00e4ltig erwogen werden. Nach \u00a7\u00a0281 Abs.\u00a04 BGB ist es dem Eigent\u00fcmer verwehrt, weiterhin Herausgabe zu verlangen, sobald er Schadensersatz statt der Leistung verlangt hat.<\/em><\/p>\n<p><strong>Eigentumsverletzung durch Einsperren eines Schiffs im Hafen<br \/>\n<\/strong>Urteil vom 21.\u00a0Juni 2016 \u2013 VI\u00a0ZR\u00a0403\/14<\/p>\n<p><em>Eine seit langem etablierte Rechtsprechung wendet der VI.\u00a0Zivilsenat auf einen aktuellen Fall an. <\/em><\/p>\n<p>Der Beklagte wollte mit einem Tankmotorschiff in einem daf\u00fcr nicht zugelassenen Bereich vor Anker gehen. Bei dem Man\u00f6ver setzte sich das Schiff so ungl\u00fccklich fest, dass die Einfahrt zu einem Yachthafen nicht mehr befahrbar war. Der Kl\u00e4ger begehrt Ersatz von Stillstandskosten f\u00fcr mehrere Schiffe, die einen Tag lang in dem Yachthafen eingeschlossen waren. Das in erster Instanz als Rheinschifffahrtsgericht zust\u00e4ndige AG erlie\u00df ein Grundurteil zugunsten des Kl\u00e4gers. Das als Rheinschifffahrtsobergericht f\u00fcr die Berufung zust\u00e4ndige OLG wies die Klage hingegen ab.<\/p>\n<p>Der BGH verweist die Sache an das OLG zur\u00fcck. Er nimmt Bezug auf seine st\u00e4ndige Rechtsprechung, wonach die Verletzung des Eigentums an einer Sache nicht nur durch eine Beeintr\u00e4chtigung der Sachsubstanz erfolgen kann, sondern auch durch eine sonstige die Eigent\u00fcmerbefugnisse treffende tats\u00e4chliche Einwirkung auf die Sache selbst, die deren Benutzung objektiv verhindert. Bei einem Schiff, das in einem Hafen eingesperrt wird, ist diese Voraussetzung in der Regel erf\u00fcllt. Entgegen der Auffassung des OLG ist nicht zus\u00e4tzlich erforderlich, dass die Beeintr\u00e4chtigung \u00fcber einen l\u00e4ngeren Zeitraum hinweg fortdauert. Die Dauer der Beeintr\u00e4chtigung ist allenfalls f\u00fcr die H\u00f6he der zu ersetzenden Sch\u00e4den von Bedeutung.<\/p>\n<p><em><span style=\"color: #ff0000\">Praxistipp:<\/span> Die Erfolgsaussicht des Gesch\u00e4digten h\u00e4ngt in solchen Konstellationen entscheidend davon ab, ob eine bestimmungsgem\u00e4\u00dfe Nutzung der Sache noch in bestimmten Grenzen m\u00f6glich war. Nur wenn dies nicht der Fall war, liegt eine Eigentumsverletzung vor. <\/em><\/p>\n<p><strong>Sachmangelbegriff nach der Schuldrechtsmodernisierung<\/strong><br \/>\nUrteil vom 15. Juni 2016 \u2013 VIII ZR 134\/14<\/p>\n<p><em>Dass der Sachmangelbegriff des \u00a7 459 BGB a.F. enger ist als derjenige des \u00a7 434 BGB in der seit 1.1.2002 geltenden Fassung, verdeutlicht der VIII. Zivilsenat in einer Entscheidung, die auch in der Tagespresse Aufmerksamkeit gefunden hat.<\/em><\/p>\n<p>Der Kl\u00e4ger hatte vom beklagten Kraftfahrzeugh\u00e4ndler \u00fcber eine Internet-Plattform im Juli 2013 einen Audi TT \u201einklusive Audi-Garantie bis 11\/2014\u201c gekauft. Schon kurz nach dem Kauf traten Motorst\u00f6rungen auf, die in einem Audi-Zentrum behoben wurden. Weitere Garantieleistungen lehnte die Audi AG in der Folgezeit mit der Begr\u00fcndung ab, es l\u00e4gen Anzeichen f\u00fcr eine Manipulation des Kilometerstands im Zeitraum vor der \u00dcbergabe des Fahrzeugs an den Kl\u00e4ger vor. Der Kl\u00e4ger begehrte daraufhin vom Beklagten die R\u00fcckabwicklung des Kaufvertrags. Seine Klage hatte in den ersten beiden Instanzen keinen Erfolg.<\/p>\n<p>Der BGH verweist die Sache an das OLG zur\u00fcck. Entgegen der Auffassung der Vorinstanzen sieht er das Nichtbestehen der im Kaufvertrag vorgesehenen Herstellergarantie als Sachmangel an. Die auf der Grundlage des fr\u00fcheren Rechts getroffene Unterscheidung zwischen Beschaffenheitsmerkmalen, deren Vorliegen einen Sachmangel im Sinne von \u00a7\u00a0459 Abs.\u00a01 BGB a.F. darstellt, und sonstigen Eigenschaften, deren Fehlen nur dann zu Gew\u00e4hrleistungsanspr\u00fcchen gem. \u00a7\u00a0459 Abs.\u00a02 BGB a.F. f\u00fchrt, wenn sie zugesichert wurden, ist auf der Grundlage des neuen Rechts obsolet. Als Beschaffenheit im Sinne von \u00a7\u00a0434 BGB n.F. sind jedenfalls auch alle zusicherungsf\u00e4higen Eigenschaften im Sinne von \u00a7\u00a0459 Abs.\u00a02 BGB a.F. anzusehen, deren Vorliegen zur vertraglichen Sollbeschaffenheit geh\u00f6rt. Davon umfasst sind alle Beziehungen der Sache zur Umwelt, die nach der Verkehrsauffassung Einfluss auf die Wertsch\u00e4tzung der Sache haben. Diese Voraussetzungen sind bei der hier in Rede stehenden Herstellergarantie erf\u00fcllt.<\/p>\n<p><em><span style=\"color: #ff0000\">Praxistipp:<\/span> Wenn der Hersteller Garantieleistungen aus einem Grund verweigert, der f\u00fcr sich gesehen bereits einen Mangel darstellt, sollten das Nacherf\u00fcllungsbegehren und die R\u00fccktrittserkl\u00e4rung des K\u00e4ufers gegen\u00fcber dem Verk\u00e4ufer vorsorglich auf beide Gr\u00fcnde gest\u00fctzt werden \u2013 in der dem Streitfall zugrunde liegenden Konstellation also nicht nur auf das Nichtbestehen der Herstellergarantie, sondern auch auf die Manipulationen am Kilometerstand. <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In Anlehnung an die sog. Montagspost beim BGH berichtet der Montagsblog w\u00f6chentlich \u00fcber ausgew\u00e4hlte aktuelle Entscheidungen. Anwendbarkeit von \u00a7\u00a0280 und \u00a7\u00a0281 BGB im Eigent\u00fcmer-Besitzer-Verh\u00e4ltnis Urteil vom 18. M\u00e4rz 2016 \u2013 V ZR 89\/15 Eine viel diskutierte Streitfrage zum Verh\u00e4ltnis zwischen \u00a7\u00a7\u00a0985\u00a0ff. BGB und den Vorschriften des allgemeinen Schuldrechts hat der V.\u00a0Zivilsenat entschieden. Eine mittlerweile insolvente [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[63,60],"tags":[],"_links":{"self":[{"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/posts\/291"}],"collection":[{"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/comments?post=291"}],"version-history":[{"count":1,"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/posts\/291\/revisions"}],"predecessor-version":[{"id":299,"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/posts\/291\/revisions\/299"}],"wp:attachment":[{"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/media?parent=291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/categories?post=291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/tags?post=291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}