{"id":3994,"date":"2026-05-12T18:07:31","date_gmt":"2026-05-12T16:07:31","guid":{"rendered":"https:\/\/blog.otto-schmidt.de\/mdr\/?p=3994"},"modified":"2026-05-12T18:07:31","modified_gmt":"2026-05-12T16:07:31","slug":"bgh-beschwer-bei-abweisung-eines-antrags-zur-abgabe-einer-eidesstattlichen-versicherung","status":"publish","type":"post","link":"https:\/\/blog.otto-schmidt.de\/mdr\/2026\/05\/12\/bgh-beschwer-bei-abweisung-eines-antrags-zur-abgabe-einer-eidesstattlichen-versicherung\/","title":{"rendered":"BGH: Beschwer bei Abweisung eines Antrags zur Abgabe einer eidesstattlichen Versicherung"},"content":{"rendered":"<p>Dem Verfahren vor dem BGH (<a href=\"https:\/\/online.otto-schmidt.de\/db\/dokument?id=rs.bgh.20260324.vizb61\/24\">Beschl. v. 24.3.2026 \u2013 VI ZB 61\/24<\/a>) lag folgender Sachverhalt zugrunde: Die Kl\u00e4gerin verlangte von dem Beklagten in einem Prozess vor dem Amtsgericht die Bezahlung von B\u00fcchern. Der Beklagte erhob eine Widerklage mit dem Antrag auf Auskunft \u00fcber die von ihm bei der Kl\u00e4gerin gespeicherten Daten, die durch Teilanerkenntnisurteil positiv beschieden wurde. Der Beklagte erweiterte die Klage sp\u00e4ter noch um den Antrag auf Abgabe einer eidesstattlichen Versicherung bez\u00fcglich der Richtigkeit und Vollst\u00e4ndigkeit der Auskunft. Das Amtsgericht wies im Schlussurteil diese Widerklage ab und lie\u00df die Berufung nicht zu. Das sodann gleichwohl mit der Berufung befasste landgericht verwarf die Berufung als unzul\u00e4ssig. Auch die Rechtsbeschwerde blieb erfolglos.<\/p>\n<p>Die entscheidende Frage ist, ob der Beklagte hier ausreichend beschwert war, um Berufung einlegen zu k\u00f6nnen. Das Landgericht war davon ausgegangen, dass die Beschwer des Beklagten 500 Euro nicht \u00fcbersteigt. Wer mit einem Antrag auf Abgabe einer eidesstattlichen Versicherung unterliegt, ist mit seinem (wirtschaftlichen) Interesse unterlegen. Hier hat der Beklagte kein wirtschaftliches Interesse verfolgt. Es ging ihm um eine Information und um seine Pers\u00f6nlichkeitsrechte. Er wollte nicht, dass die Kl\u00e4gerin seine Daten zu Werbezwecken nutzt und er m\u00f6glicherweise mit gleichnamigen anderen Personen verwechselt wird. Entsprechend der Rechtsprechung zur DS-GVO ist daher vorliegend ein Ansatz von 500 Euro nicht zu beanstanden. Ein Ermessensfehler des Berufungsgerichts bei der Wertfestsetzung liegt damit nicht vor.<\/p>\n<p>Dies wiederum bedeutet, dass die Mindestbeschwer f\u00fcr eine Berufung (\u00a7 511 Abs. 2 Nr. 1 ZPO) nicht erreicht wird. Damit hat das Landgericht die Berufung zurecht verworfen, weswegen auch die Rechtsbeschwerde gegen diesen Beschluss erfolglos bleibt.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dem Verfahren vor dem BGH (Beschl. v. 24.3.2026 \u2013 VI ZB 61\/24) lag folgender Sachverhalt zugrunde: Die Kl\u00e4gerin verlangte von dem Beklagten in einem Prozess vor dem Amtsgericht die Bezahlung von B\u00fcchern. Der Beklagte erhob eine Widerklage mit dem Antrag auf Auskunft \u00fcber die von ihm bei der Kl\u00e4gerin gespeicherten Daten, die durch Teilanerkenntnisurteil positiv [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1305,2],"tags":[3775,199,3776],"_links":{"self":[{"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/posts\/3994"}],"collection":[{"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/comments?post=3994"}],"version-history":[{"count":1,"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/posts\/3994\/revisions"}],"predecessor-version":[{"id":3995,"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/posts\/3994\/revisions\/3995"}],"wp:attachment":[{"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/media?parent=3994"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/categories?post=3994"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.otto-schmidt.de\/mdr\/wp-json\/wp\/v2\/tags?post=3994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}