{"id":1948,"date":"2026-07-14T10:08:40","date_gmt":"2026-07-14T08:08:40","guid":{"rendered":"https:\/\/blog.otto-schmidt.de\/zkm-report\/?p=1948"},"modified":"2026-07-14T10:08:40","modified_gmt":"2026-07-14T08:08:40","slug":"schiedsverfahren-gewinnen-bei-patentstreitigkeiten-an-bedeutung","status":"publish","type":"post","link":"https:\/\/blog.otto-schmidt.de\/zkm-report\/2026\/07\/14\/schiedsverfahren-gewinnen-bei-patentstreitigkeiten-an-bedeutung\/","title":{"rendered":"Schiedsverfahren gewinnen bei Patentstreitigkeiten an Bedeutung"},"content":{"rendered":"<p>Auch Patentstreitigkeiten werden zunehmend nicht mehr vor staatlichen Gerichten, sondern im Wege der Schiedsgerichtsbarkeit beigelegt. Darauf weisen die Freshfields-Partner Dr. Nina Bayerl und Dr. Boris Kasolowsky in einem Gastbeitrag der B\u00f6rsen-Zeitung hin. Die Trend spiegelt die wirtschaftliche Bedeutung von Patenten wider \u2013 insbesondere in Hightech-Branchen (wie etwa Life Sciences und Mikroelektronik) sowie die zunehmende internationale Verflechtung von Patentportfolios wider. Unternehmen suchen vor diesem Hintergrund nach effizienten, vertraulichen und international durchsetzbaren Streitbeilegungsmechanismen.<\/p>\n<p>Klassische Patentprozesse bleiben \u2013 trotz j\u00fcngerer Entwicklungen in Richtung von grenz\u00fcberschreitenden Entscheidungen \u2013h\u00e4ufig auf einzelne Jurisdiktionen beschr\u00e4nkt, sind kostenintensiv und dauern oft mehrere Jahre. Zudem bergen parallele Verfahren in verschiedenen L\u00e4ndern das Risiko widerspr\u00fcchlicher Entscheidungen. Schiedsverfahren erm\u00f6glichen demgegen\u00fcber die B\u00fcndelung patentbezogener Streitigkeiten in einem zentralen Forum. Besonders relevant ist die internationale Vollstreckbarkeit von Schiedsspr\u00fcchen nach dem New Yorker \u00dcbereinkommen von 1958., das eine relativ vorhersehbare und weitreichende Durchsetzung in nahezu allen relevanten Wirtschaftsr\u00e4umen erm\u00f6glicht.<\/p>\n<p>Ein bekanntes Beispiel f\u00fcr die Herausforderungen multinationaler Patentstreitigkeiten war der globale Konflikt zwischen AutoStore und Ocado, der Verfahren in Gro\u00dfbritannien, den USA, Deutschland sowie vor dem Europ\u00e4ische Patentamt umfasste und erst 2023 durch eine weltweite Einigung mit umfassenden Kreuzlizenzen beendete wurde.<\/p>\n<p>Auch in internationalen Lizenzstreitigkeiten \u2013 etwa bei der Auslegung und Durchsetzung von Lizenzvertr\u00e4gen oder bei standardessenzielle Patente (SEPs) und FRAND-Lizenzbedingungen \u2013 wird die Schiedsgerichtsbarkeit genutzt. Da technische Standards global gelten, sind auch die zugrunde liegenden Lizenzbeziehungen international ausgestaltet; entsprechend stellt die Schiedsgerichtsbarkeit eine praktisch h\u00e4ufig genutzte Alternative zur gerichtlichen Festsetzungen globaler Lizenzgeb\u00fchren.<\/p>\n<p>Neben der Schiedsgerichtsbarkeit nennen die Autoren auch Mediation als Option zu Beilegung komplexer Auseinandersetzungen. Institutionalisierte Mediationsangebote bestehen etwa bei der ICC oder JAMS.<\/p>\n<p>Schub erh\u00e4lt die Patent-Schiedsgerichtsbarkeit durch spezialisierte Prozessregeln der Schiedsinstitute. Ein Meilenstein waren die 1994 eingef\u00fchrten WIPO-Schiedsregeln. Ein weiterer wichtiger Schritt wird das im Juni 2026 er\u00f6ffnete \u201eMediations- und Schiedszentrums f\u00fcr Patentsachen (MSZP\/PMAC)\u201c des Einheitlichen Patentgerichts sein. Die dort vorgesehenen Regeln sollen sowohl beim UPC anh\u00e4ngige Verfahren als auch komplexe, multinationale Streitigkeiten mit au\u00dfereurop\u00e4ischem Bezug erfassen.<\/p>\n<p><em>Quelle: boersen-zeitung.de v. 13.05.2026<\/em><\/p>\n<p>Bild: \u00a9Katsiaryna &#8211; stock.adobe.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Auch Patentstreitigkeiten werden zunehmend nicht mehr vor staatlichen Gerichten, sondern im Wege der Schiedsgerichtsbarkeit beigelegt. Darauf weisen die Freshfields-Partner Dr. Nina Bayerl und Dr. Boris Kasolowsky in einem Gastbeitrag der B\u00f6rsen-Zeitung hin. Die Trend spiegelt die wirtschaftliche Bedeutung von Patenten wider \u2013 insbesondere in Hightech-Branchen (wie etwa Life Sciences und Mikroelektronik) sowie die zunehmende internationale Verflechtung von Patentportfolios wider. Unternehmen suchen vor diesem Hintergrund nach effizienten, vertraulichen und international durchsetzbaren Streitbeilegungsmechanismen. Klassische Patentprozesse bleiben \u2013 trotz j\u00fcngerer Entwicklungen in Richtung von grenz\u00fcberschreitenden Entscheidungen \u2013h\u00e4ufig auf einzelne Jurisdiktionen beschr\u00e4nkt, sind kostenintensiv und dauern oft mehrere Jahre. Zudem bergen parallele Verfahren in verschiedenen L\u00e4ndern das Risiko widerspr\u00fcchlicher Entscheidungen. Schiedsverfahren erm\u00f6glichen demgegen\u00fcber die B\u00fcndelung patentbezogener Streitigkeiten in einem zentralen Forum. Besonders relevant ist die internationale Vollstreckbarkeit von Schiedsspr\u00fcchen nach dem New Yorker \u00dcbereinkommen von 1958., das eine relativ vorhersehbare und weitreichende Durchsetzung in nahezu allen relevanten Wirtschaftsr\u00e4umen erm\u00f6glicht. Ein bekanntes Beispiel f\u00fcr die Herausforderungen multinationaler Patentstreitigkeiten war der globale Konflikt zwischen AutoStore und Ocado, der Verfahren in Gro\u00dfbritannien, den USA, Deutschland sowie vor dem Europ\u00e4ische Patentamt umfasste und erst 2023 durch eine weltweite Einigung mit umfassenden Kreuzlizenzen beendete wurde. Auch in internationalen Lizenzstreitigkeiten \u2013 etwa bei der Auslegung und Durchsetzung von Lizenzvertr\u00e4gen oder [&hellip;]<\/p>\n","protected":false},"author":80,"featured_media":1960,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[644],"tags":[8,660,658,517,659],"_links":{"self":[{"href":"https:\/\/blog.otto-schmidt.de\/zkm-report\/wp-json\/wp\/v2\/posts\/1948"}],"collection":[{"href":"https:\/\/blog.otto-schmidt.de\/zkm-report\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.otto-schmidt.de\/zkm-report\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.otto-schmidt.de\/zkm-report\/wp-json\/wp\/v2\/users\/80"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.otto-schmidt.de\/zkm-report\/wp-json\/wp\/v2\/comments?post=1948"}],"version-history":[{"count":2,"href":"https:\/\/blog.otto-schmidt.de\/zkm-report\/wp-json\/wp\/v2\/posts\/1948\/revisions"}],"predecessor-version":[{"id":1961,"href":"https:\/\/blog.otto-schmidt.de\/zkm-report\/wp-json\/wp\/v2\/posts\/1948\/revisions\/1961"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.otto-schmidt.de\/zkm-report\/wp-json\/wp\/v2\/media\/1960"}],"wp:attachment":[{"href":"https:\/\/blog.otto-schmidt.de\/zkm-report\/wp-json\/wp\/v2\/media?parent=1948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.otto-schmidt.de\/zkm-report\/wp-json\/wp\/v2\/categories?post=1948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.otto-schmidt.de\/zkm-report\/wp-json\/wp\/v2\/tags?post=1948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}